{"id":589,"date":"2016-08-19T20:36:32","date_gmt":"2016-08-20T00:36:32","guid":{"rendered":"http:\/\/arpenterlechemin.com\/?p=589"},"modified":"2019-09-12T14:16:39","modified_gmt":"2019-09-12T18:16:39","slug":"mes-bonnes-tables-abordables-a-quebec","status":"publish","type":"post","link":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/","title":{"rendered":"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec"},"content":{"rendered":"<p>Un avantage de voyager avec la famille, c&rsquo;est de d\u00e9couvrir des \u00e9tablissements o\u00f9 on ne serait jamais all\u00e9s de nous-m\u00eames. L\u00e0 o\u00f9 nous sommes des grands habitu\u00e9s des sandwicheries, cr\u00eaperies, restaus petits prix, voire tr\u00e8s honn\u00eatement tout simplement du bar \u00e0 taboul\u00e9 du supermarch\u00e9, la famille, elle, aime les Restaurants.<\/p>\n<p>Entendre par l\u00e0 les Bons Restaurants. Majuscules voulues. Les grands restaurants, ceux o\u00f9 on est bien servis, o\u00f9 on mange bien, o\u00f9 l&rsquo;addition co\u00fbte plus cher que notre loyer (\u00e0 peu de choses pr\u00e8s).<\/p>\n<p>Donc autant dire que pendant ma petite escapade \u00e0 <a href=\"http:\/\/arpenterlechemin.com\/index.php\/tag\/quebec\">Qu\u00e9bec<\/a> l&rsquo;an dernier avec la famille, j&rsquo;ai eu la chance d&rsquo;aller dans des Bons Restaurants. Rien d&rsquo;exorbitant au niveau de l&rsquo;addition, mais la f\u00eate dans mes papilles. Oh \u00e7a oui.<\/p>\n<h3><span style=\"color: #000080;\"><strong>Le Lapin Saut\u00e9<\/strong>,<\/span> 52 rue du Petit Champlain<\/h3>\n<p>Ce <a href=\"http:\/\/www.lapinsaute.com\/francais\/les-menus\/\">restaurant<\/a> nous a s\u00e9duit avec\u00a0sa terrasse, et nos attentes \u00e9taient inversement proportionnelles \u00e0 sa situation, en pleine vieille ville, en pleine rue \u00e0 touristes (mais <a href=\"http:\/\/arpenterlechemin.com\/index.php\/2017\/12\/26\/vieux-quebec-temps-fetes\/\">belle, la rue \u00e0 touristes<\/a> !). En cas de d\u00e9ception, on s&rsquo;\u00e9tait dit qu&rsquo;on aurait toujours eu l&rsquo;occasion de manger dans un bel endroit&#8230;<\/p>\n<p>Et comme assez rarement\u00a0dans ce genre de cas, nous avons \u00e9t\u00e9 ravies. Mais vraiment.<\/p>\n<p>Je me sentais l&rsquo;humeur l\u00e9g\u00e8re, et j&rsquo;ai donc command\u00e9 deux entr\u00e9es : ch\u00e8vre chaud d\u2019Alexis de Portneuf et poires \u00e0 l\u2019\u00e9rable, et <a href=\"http:\/\/www.fromagesileauxgrues.com\/riopelle-de-isle-fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Riopelle-de-l\u2019\u00eele-aux-Grues<\/a> fondant, compote de courge musqu\u00e9e.<\/p>\n<p>Les saveurs fondent dans la bouche, les associations \u00e9tonnent, c&rsquo;est le feu d&rsquo;artifice. Le restaurant propose aussi des plats savoureux\u00a0comme du gravlax de truite au <a href=\"http:\/\/arpenterlechemin.com\/index.php\/2017\/08\/29\/terre-neuve-bienvenue-au-parc-national-de-gros-morne\/\">th\u00e9 du Labrador<\/a>, de la f\u00eata ch\u00e8vre chaud, de la terrine de lapin qui ravit ma m\u00e8re.\u00a0Sans oublier de la cr\u00e8me br\u00fbl\u00e9e \u00e0 l&rsquo;\u00e9rable, et de la tarte au miel sal\u00e9 pour les becs sucr\u00e9s.<\/p>\n<p>Et \u00e9videmment, parce qu&rsquo;on reste en plein Qu\u00e9bec touristique, de la poutine. Mais au lapin, la poutine, oui madame.<\/p>\n<p>Seul b\u00e9mol, j&rsquo;ai \u00e9t\u00e9 un peu d\u00e9\u00e7ue des quantit\u00e9s mais je me console en me disant que mes papilles ont eu droit \u00e0 un traitement qualitatif et non quantitatif.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-394 size-full\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090115.jpg\" alt=\"_1090115\" width=\"4592\" height=\"3448\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090115.jpg 4592w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090115-300x225.jpg 300w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090115-768x577.jpg 768w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090115-1024x769.jpg 1024w\" sizes=\"(max-width: 4592px) 100vw, 4592px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Ch\u00e8vre chaud d\u2019Alexis de Portneuf et poires \u00e0 l\u2019\u00e9rable<\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-395 size-full\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090116.jpg\" alt=\"_1090116\" width=\"4592\" height=\"3448\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090116.jpg 4592w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090116-300x225.jpg 300w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090116-768x577.jpg 768w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090116-1024x769.jpg 1024w\" sizes=\"(max-width: 4592px) 100vw, 4592px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Riopelle-de-l\u2019\u00eele-aux-Grues fondant, compote de courge musqu\u00e9e<\/em><\/p>\n<h3><span style=\"color: #003366;\"><strong>Aviatic<\/strong>,<\/span> dans la gare du Palais<\/h3>\n<p>En parlant de quantit\u00e9, parlons tout de suite des choses qui f\u00e2chent avec <a href=\"http:\/\/aviatic.ca\">Aviatic<\/a>. Je suis v\u00e9g\u00e9tarienne. Je n&rsquo;en ai pas moins l&rsquo;estomac d&rsquo;un \u00eatre humain de taille normale. L&rsquo;estomac d&rsquo;un humain de taille normale ne peut pas se contenter, en aucune circonstances, de cinq tomates cerise.<\/p>\n<p>Et ce, m\u00eame si elles sont sublimes. Mais au moins, elles \u00e9taient sublimes, tout comme l&rsquo;espuma de bocconcini. Il est vrai que le seul plat v\u00e9g\u00e9tarien de la carte <em>[\u00e0 l&rsquo;\u00e9poque &#8211; apr\u00e8s v\u00e9rification, le c\u00f4t\u00e9 v\u00e9g\u00e9tarien du menu s&rsquo;est bien \u00e9toff\u00e9, avec cinq options]<\/em> \u00e9tait une entr\u00e9e, mais disons que cela m&rsquo;a donn\u00e9 un pr\u00e9texte pour prendre un dessert, cons\u00e9quent celui-ci : un\u00a0g\u00e2teau aux carottes \u00e0 \u00e9tages et Messerschmidt (fondant au chocolat) frit. Un r\u00e9gal, malgr\u00e9 la texture inattendue du fondant frit !<\/p>\n<p>Les autres convives, quant \u00e0 elles, avaient le choix entre des plats aussi vari\u00e9s que du tataki de filet de boeuf, une noix de cerf r\u00f4tie, pieuvre d&rsquo;Espagne et flanc de porc\u00a0Nagano, ravioli de crabes et crevettes&#8230; Que du bon !<\/p>\n<p>Au niveau de l&rsquo;ambiance, Aviatic joue \u00e0 fond la carte \u00ab\u00a0voyage des ann\u00e9es 1920\u00a0\u00bb avec un c\u00f4t\u00e9 feutr\u00e9 et serveurs en gants blancs.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-392 size-full\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090073.jpg\" alt=\"_1090073\" width=\"4592\" height=\"3448\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090073.jpg 4592w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090073-300x225.jpg 300w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090073-768x577.jpg 768w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090073-1024x769.jpg 1024w\" sizes=\"(max-width: 4592px) 100vw, 4592px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Tomates de serre et espuma de bocconcini, pistaches, balsamique et huile d&rsquo;herbes<\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-393 size-full\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090076.jpg\" alt=\"_1090076\" width=\"4592\" height=\"3448\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090076.jpg 4592w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090076-300x225.jpg 300w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090076-768x577.jpg 768w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090076-1024x769.jpg 1024w\" sizes=\"(max-width: 4592px) 100vw, 4592px\" \/><\/p>\n<h3><span style=\"color: #000080;\"><strong>Chez Boulay, bistro bor\u00e9al<\/strong>,<\/span> 1110 rue Saint-Jean<\/h3>\n<p>On commence \u00e0 s&rsquo;attaquer aux choses s\u00e9rieuses. Rien que le <a href=\"http:\/\/chezboulay.com\">nom<\/a> me pla\u00eet. Le concept aussi : de la cuisine bor\u00e9ale p\u00e9trie d&rsquo;influences nordiques, qui met \u00e0 l&rsquo;honneur les baies, les l\u00e9gumes de saison, les champignons, le poisson, o\u00f9 les saveurs du Nord s&rsquo;invitent \u00e0 la table en une bien belle symphonie. L&rsquo;endroit a du succ\u00e8s et \u00e7a se voit : salle comble un soir de semaine, un peu bruyante comme partout au <a href=\"http:\/\/arpenterlechemin.com\/index.php\/tag\/canada\">Canada<\/a>, mais un service attentionn\u00e9 et efficace dans un beau cadre.<\/p>\n<p>Pour ma part, je jette mon d\u00e9volu sur les\u00a0betteraves du terroir marin\u00e9es au sirop de merisier, ch\u00e8vre des Neiges d\u2019Alexis de Portneuf en entr\u00e9e, suivies de gnocchi gratin\u00e9s\u00a0\u00e0 la graine de carotte sauvage et tomme de Monsieur S\u00e9guin. Les quantit\u00e9s sont parfaites, et c&rsquo;est l&rsquo;extase culinaire.<\/p>\n<p>Pour vous donner envie, le menu du moment propose des perles comme le carpaccio d\u2019omble de l\u2019arctique, marinade autour du sureau,\u00a0coeur de quenouille, ascl\u00e9piade et \u00e9mulsion d\u2019herbes ; le tatin de\u00a0betterave au sirop de bouleau, espuma au fromage Ch\u00e8vre des Neiges, riz sauvage souffl\u00e9, ou encore le risotto d\u2019orge au ma\u00efs et algues, sauce vierge au balsamique de cassis biologique \u00c9lia. Bien d&rsquo;autres merveilles vous attendent, mais je manque un peu de place pour tous les d\u00e9crire.<\/p>\n<p>Le bon point qui fait plaisir : un vrai choix de plats v\u00e9g\u00e9tariens !<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-396 size-full\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090156.jpg\" alt=\"_1090156\" width=\"4592\" height=\"3448\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090156.jpg 4592w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090156-300x225.jpg 300w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090156-768x577.jpg 768w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090156-1024x769.jpg 1024w\" sizes=\"(max-width: 4592px) 100vw, 4592px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Gnocchi gratin\u00e9s\u00a0\u00e0 la graine de carotte sauvage et tomme de Monsieur S\u00e9guin<\/em><\/p>\n<h3><span style=\"color: #000080;\"><strong>L\u00e9gende chez la Tani\u00e8re<\/strong>,<\/span> 2115 Rang Saint Ange<\/h3>\n<p>Celui-l\u00e0, je le garde pour la fin, comme une cerise sur le g\u00e2teau. Autant pour les restaurants pr\u00e9c\u00e9dents, nous nous \u00e9tions renseign\u00e9es, avions consult\u00e9 des menus, avions savour\u00e9 l&rsquo;attente d&rsquo;aller bien manger&#8230; Autant pour ce <a href=\"http:\/\/restaurantlataniere.com\/\">restaurant<\/a>, ce fut la surprise totale.<\/p>\n<p>Perdues dans un quartier o\u00f9 rien n&rsquo;\u00e9tait vraiment ouvert ce jour-l\u00e0, nous avons tourn\u00e9 longtemps avant de tomber sur une fa\u00e7ade un peu \u00e9clair\u00e9es&#8230; Nous rentrons, l&rsquo;estomac dans le talon. Le cadre est beau, \u00e0 nouveau une ambiance bor\u00e9ale avec des troncs de bouleaux et des fourrures, l&rsquo;esth\u00e9tique est\u00a0prometteuse d&rsquo;un beau moment. Je consulte la carte, et c&rsquo;est le drame : une carte courte, manifestement des produits de saison, mais rien de v\u00e9g\u00e9tarien. Je m&rsquo;appr\u00eate \u00e0 rebrousser chemin quand un membre du personnel se pr\u00e9sente. Je lui fais part de mon d\u00e9sir de repartir, peut-\u00eatre un peu s\u00e8chement, puisque je ne peux rien manger. Il ne se laissera pas d\u00e9monter et me propose d&rsquo;aller en parler au chef. Gloire lui soit rendue ! J&rsquo;ai laiss\u00e9 un pourboire de folie.<\/p>\n<p>Autant vous dire que je n&rsquo;attendais rien d&rsquo;un plat bricol\u00e9 \u00e0 la derni\u00e8re minute. Et pourtant. Et pourtant !<\/p>\n<p>Lentilles, topinambour et t\u00eates de violons en entr\u00e9e. Croquettes de tofu, courge et c\u00e9leri en plat.<\/p>\n<p>Dit comme \u00e7a, \u00e7a semble simple, mais les saveurs \u00e9taient accord\u00e9es \u00e0 la perfection, tout se mariait \u00e0 merveille, j&rsquo;en suis ressortie avec l&rsquo;impression d&rsquo;avoir mang\u00e9 le meilleur repas de ma vie. Rien que \u00e7a.<\/p>\n<p>Parmi les autres plats au menu : tataki de cerf,\u00a0quinoa, endive r\u00f4ti, tomate babeurre\u00a0; omble chevalier fum\u00e9,\u00a0feuille de Bruxelles, sauce c\u00e9sar au hareng fum\u00e9, bouton de marguerite ; souffl\u00e9 glac\u00e9 \u00e0 la camerise,\u00a0rhubarbe poch\u00e9e, gin infus\u00e9 au cassis.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-397 size-full\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090171.jpg\" alt=\"_1090171\" width=\"4592\" height=\"3448\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090171.jpg 4592w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090171-300x225.jpg 300w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090171-768x577.jpg 768w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090171-1024x769.jpg 1024w\" sizes=\"(max-width: 4592px) 100vw, 4592px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Lentilles, topinambour et t\u00eates de violons<\/em> <img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-398 size-full\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090172.jpg\" alt=\"_1090172\" width=\"4592\" height=\"3448\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090172.jpg 4592w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090172-300x225.jpg 300w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090172-768x577.jpg 768w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/1090172-1024x769.jpg 1024w\" sizes=\"(max-width: 4592px) 100vw, 4592px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Croquettes de tofu, courge et c\u00e9leri\u00a0<\/em><\/p>\n<h3><strong><span style=\"color: #0000ff;\">Et le budget dans tout \u00e7a ?<\/span><\/strong><\/h3>\n<p>Et bien, c&rsquo;est \u00e9tonnant pour une telle qualit\u00e9, mais les\u00a0plats pr\u00e9sent\u00e9s ici n&rsquo;ont jamais d\u00e9pass\u00e9 la trentaine de dollars (environ 20 euros). Une telle qualit\u00e9 \u00e0 un tel prix&#8230; j&rsquo;y retourne d\u00e8s que j&rsquo;ai le courage de refaire les <a href=\"http:\/\/arpenterlechemin.com\/index.php\/2016\/09\/23\/a-toutes-les-nuits-blanches-sur-la-route\/\">13 heures de train <\/a>entre <a href=\"https:\/\/arpenterlechemin.com\/index.php\/2019\/07\/17\/que-faire-moncton\/\">Moncton <\/a>et\u00a0Qu\u00e9bec !<\/p>\n<h3><span style=\"color: #000080;\">O\u00f9 dormir \u00e0 Qu\u00e9bec<\/span><\/h3>\n<ul>\n<li>pour les petits budgets \u00e0 Qu\u00e9bec, le plus simple reste encore l&rsquo;<a href=\"https:\/\/www.booking.com\/hotel\/ca\/auberge-international-de-quebec.en.html?aid=1571475&amp;no_rooms=1&amp;group_adults=1\">Auberge internationale de Qu\u00e9bec<\/a> ou l&rsquo;auberge <a href=\"https:\/\/www.booking.com\/hotel\/ca\/auberge-jeunesse-planete-backpackers-hostel.en.html?aid=1571475&amp;no_rooms=1&amp;group_adults=1\">La belle plan\u00e8te<\/a><\/li>\n<li>au niveau des g\u00eetes, j&rsquo;ai rep\u00e9r\u00e9 le <a href=\"https:\/\/www.booking.com\/hotel\/ca\/b-b-maison-historique-james-thompson.en.html?aid=1571475&amp;no_rooms=1&amp;group_adults=1\">B&amp;b Maison historique James Thompson<\/a> ou le <a href=\"https:\/\/www.booking.com\/hotel\/ca\/b-b-des-grisons-ville-de-quebec.en.html?aid=1571475&amp;no_rooms=1&amp;group_adults=1\">B&amp;B des Grisons<\/a><\/li>\n<li>pour une exp\u00e9rience insolite, pourquoi ne pas essayer le <a href=\"https:\/\/www.booking.com\/hotel\/ca\/monastere-des-augustines.en.html?aid=1571475&amp;no_rooms=1&amp;group_adults=1\">Monast\u00e8re des Augustines<\/a>, un ancien couvent transform\u00e9 en h\u00f4tel ? Charme garanti !<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.booking.com\/index.html?aid=1571475\"><em>R\u00e9servez votre h\u00f4tel en ligne \u00e0 Qu\u00e9bec<\/em><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/tracking.publicidees.com\/clic.php?partid=56598&amp;progid=1700&amp;promoid=110889\"><em>R\u00e9servez votre vol entre le Qu\u00e9bec et la France<\/em><\/a><\/p>\n<p>Si vous avez aim\u00e9, n&rsquo;h\u00e9sitez pas \u00e0 m&rsquo;\u00e9pingler sur <a href=\"https:\/\/www.pinterest.fr\/arpenterlechemin\">Pinterest\u00a0<\/a>et \u00e0 <a href=\"http:\/\/eepurl.com\/cbyYcP\">vous abonner<\/a> pour ne rien rater ! Oyez, oyez. Ce billet contient des<a href=\"http:\/\/arpenterlechemin.com\/index.php\/2018\/12\/01\/soutenir-blog\/\"> liens affili\u00e9s.<\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-6799\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bonnes-tables-quebec-petit-champlain-bien-manger-blog-voyage-road-trip-canada-arpenter-le-chemin-267x400.jpg\" alt=\"bonnes tables quebec petit-champlain bien manger blog voyage road-trip canada arpenter le chemin\" width=\"267\" height=\"400\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bonnes-tables-quebec-petit-champlain-bien-manger-blog-voyage-road-trip-canada-arpenter-le-chemin-267x400.jpg 267w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bonnes-tables-quebec-petit-champlain-bien-manger-blog-voyage-road-trip-canada-arpenter-le-chemin-390x585.jpg 390w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bonnes-tables-quebec-petit-champlain-bien-manger-blog-voyage-road-trip-canada-arpenter-le-chemin.jpg 735w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-6800\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/quebec-bonnes-tables-bien-manger-petit-champlain-restaurants-bonnes-adresses-blog-voyage-canada-arpenter-le-chemin-267x400.jpg\" alt=\"quebec bonnes tables bien manger petit-champlain restaurants bonnes adresses blog voyage canada arpenter le chemin\" width=\"267\" height=\"400\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/quebec-bonnes-tables-bien-manger-petit-champlain-restaurants-bonnes-adresses-blog-voyage-canada-arpenter-le-chemin-267x400.jpg 267w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/quebec-bonnes-tables-bien-manger-petit-champlain-restaurants-bonnes-adresses-blog-voyage-canada-arpenter-le-chemin-390x585.jpg 390w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/quebec-bonnes-tables-bien-manger-petit-champlain-restaurants-bonnes-adresses-blog-voyage-canada-arpenter-le-chemin.jpg 735w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-6801\" src=\"http:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bien-manger-bonnes-tables-vieux-quebec-petit-champlain-blog-voyage-road-trip-canada-arpenter-le-chemin-267x400.jpg\" alt=\"bien manger bonnes tables vieux quebec petit-champlain blog voyage road-trip canada arpenter le chemin\" width=\"267\" height=\"400\" srcset=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bien-manger-bonnes-tables-vieux-quebec-petit-champlain-blog-voyage-road-trip-canada-arpenter-le-chemin-267x400.jpg 267w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bien-manger-bonnes-tables-vieux-quebec-petit-champlain-blog-voyage-road-trip-canada-arpenter-le-chemin-390x585.jpg 390w, https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/bien-manger-bonnes-tables-vieux-quebec-petit-champlain-blog-voyage-road-trip-canada-arpenter-le-chemin.jpg 735w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/><\/p>\n<p><em>Bons plans, bonnes adresses ou anecdotes&#8230; Je veux tout savoir en commentaire !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un avantage de voyager avec la famille, c&rsquo;est de d\u00e9couvrir des \u00e9tablissements o\u00f9 on ne serait jamais all\u00e9s de nous-m\u00eames. <\/p>\n","protected":false},"author":1,"featured_media":400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false},"categories":[526,539,1],"tags":[611,42,7],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec - Arpenter le chemin<\/title>\n<meta name=\"description\" content=\"O\u00f9 bien manger \u00e0 Qu\u00e9bec sans trop d\u00e9penser : bonnes adresses pour trouver de bonnes tables dans la vieille ville de Qu\u00e9bec...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec - Arpenter le chemin\" \/>\n<meta property=\"og:description\" content=\"O\u00f9 bien manger \u00e0 Qu\u00e9bec sans trop d\u00e9penser : bonnes adresses pour trouver de bonnes tables dans la vieille ville de Qu\u00e9bec...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/\" \/>\n<meta property=\"og:site_name\" content=\"Arpenter le chemin\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-20T00:36:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-12T18:16:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/Titre-tables-Qu\u00e9bec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2638\" \/>\n\t<meta property=\"og:image:height\" content=\"1981\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Audrey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Audrey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/\"},\"author\":{\"name\":\"Audrey\",\"@id\":\"https:\/\/arpenterlechemin.com\/#\/schema\/person\/1d187818c0988fbea4d682c1e59c795c\"},\"headline\":\"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec\",\"datePublished\":\"2016-08-20T00:36:32+00:00\",\"dateModified\":\"2019-09-12T18:16:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/\"},\"wordCount\":1434,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/arpenterlechemin.com\/#organization\"},\"keywords\":[\"bonnes adresses\",\"canada\",\"qu\u00e9bec\"],\"articleSection\":[\"Am\u00e9rique du Nord\",\"Am\u00e9riques\",\"Blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/\",\"url\":\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/\",\"name\":\"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec - Arpenter le chemin\",\"isPartOf\":{\"@id\":\"https:\/\/arpenterlechemin.com\/#website\"},\"datePublished\":\"2016-08-20T00:36:32+00:00\",\"dateModified\":\"2019-09-12T18:16:39+00:00\",\"description\":\"O\u00f9 bien manger \u00e0 Qu\u00e9bec sans trop d\u00e9penser : bonnes adresses pour trouver de bonnes tables dans la vieille ville de Qu\u00e9bec...\",\"breadcrumb\":{\"@id\":\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/arpenterlechemin.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arpenterlechemin.com\/#website\",\"url\":\"https:\/\/arpenterlechemin.com\/\",\"name\":\"Arpenter le chemin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/arpenterlechemin.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arpenterlechemin.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arpenterlechemin.com\/#organization\",\"name\":\"Arpenter le chemin\",\"url\":\"https:\/\/arpenterlechemin.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arpenterlechemin.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2017\/04\/icone-4.jpg\",\"contentUrl\":\"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2017\/04\/icone-4.jpg\",\"width\":150,\"height\":73,\"caption\":\"Arpenter le chemin\"},\"image\":{\"@id\":\"https:\/\/arpenterlechemin.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/arpenterlechemin.com\/#\/schema\/person\/1d187818c0988fbea4d682c1e59c795c\",\"name\":\"Audrey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arpenterlechemin.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b75298f64c73f1709976c50921beae6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b75298f64c73f1709976c50921beae6a?s=96&d=mm&r=g\",\"caption\":\"Audrey\"},\"description\":\"Allergique \u00e0 la routine, atteinte de bougeotte aigu\u00eb, j'essaie de m'envoler aussi souvent que possible, seule, en couple ou entre amis ! Ville, nature, culture, rando... tout me va, \u00e0 partir du moment o\u00f9 je suis dehors.\",\"url\":\"https:\/\/arpenterlechemin.com\/index.php\/author\/audreyf\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec - Arpenter le chemin","description":"O\u00f9 bien manger \u00e0 Qu\u00e9bec sans trop d\u00e9penser : bonnes adresses pour trouver de bonnes tables dans la vieille ville de Qu\u00e9bec...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/","og_locale":"fr_FR","og_type":"article","og_title":"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec - Arpenter le chemin","og_description":"O\u00f9 bien manger \u00e0 Qu\u00e9bec sans trop d\u00e9penser : bonnes adresses pour trouver de bonnes tables dans la vieille ville de Qu\u00e9bec...","og_url":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/","og_site_name":"Arpenter le chemin","article_published_time":"2016-08-20T00:36:32+00:00","article_modified_time":"2019-09-12T18:16:39+00:00","og_image":[{"width":2638,"height":1981,"url":"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/Titre-tables-Qu\u00e9bec.jpg","type":"image\/jpeg"}],"author":"Audrey","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Audrey","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#article","isPartOf":{"@id":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/"},"author":{"name":"Audrey","@id":"https:\/\/arpenterlechemin.com\/#\/schema\/person\/1d187818c0988fbea4d682c1e59c795c"},"headline":"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec","datePublished":"2016-08-20T00:36:32+00:00","dateModified":"2019-09-12T18:16:39+00:00","mainEntityOfPage":{"@id":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/"},"wordCount":1434,"commentCount":3,"publisher":{"@id":"https:\/\/arpenterlechemin.com\/#organization"},"keywords":["bonnes adresses","canada","qu\u00e9bec"],"articleSection":["Am\u00e9rique du Nord","Am\u00e9riques","Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/","url":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/","name":"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec - Arpenter le chemin","isPartOf":{"@id":"https:\/\/arpenterlechemin.com\/#website"},"datePublished":"2016-08-20T00:36:32+00:00","dateModified":"2019-09-12T18:16:39+00:00","description":"O\u00f9 bien manger \u00e0 Qu\u00e9bec sans trop d\u00e9penser : bonnes adresses pour trouver de bonnes tables dans la vieille ville de Qu\u00e9bec...","breadcrumb":{"@id":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arpenterlechemin.com\/index.php\/2016\/08\/19\/mes-bonnes-tables-abordables-a-quebec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arpenterlechemin.com\/"},{"@type":"ListItem","position":2,"name":"QU\u00c9BEC \/\/ Mes bonnes tables \u00e0 Qu\u00e9bec"}]},{"@type":"WebSite","@id":"https:\/\/arpenterlechemin.com\/#website","url":"https:\/\/arpenterlechemin.com\/","name":"Arpenter le chemin","description":"","publisher":{"@id":"https:\/\/arpenterlechemin.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arpenterlechemin.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/arpenterlechemin.com\/#organization","name":"Arpenter le chemin","url":"https:\/\/arpenterlechemin.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arpenterlechemin.com\/#\/schema\/logo\/image\/","url":"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2017\/04\/icone-4.jpg","contentUrl":"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2017\/04\/icone-4.jpg","width":150,"height":73,"caption":"Arpenter le chemin"},"image":{"@id":"https:\/\/arpenterlechemin.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/arpenterlechemin.com\/#\/schema\/person\/1d187818c0988fbea4d682c1e59c795c","name":"Audrey","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arpenterlechemin.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b75298f64c73f1709976c50921beae6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b75298f64c73f1709976c50921beae6a?s=96&d=mm&r=g","caption":"Audrey"},"description":"Allergique \u00e0 la routine, atteinte de bougeotte aigu\u00eb, j'essaie de m'envoler aussi souvent que possible, seule, en couple ou entre amis ! Ville, nature, culture, rando... tout me va, \u00e0 partir du moment o\u00f9 je suis dehors.","url":"https:\/\/arpenterlechemin.com\/index.php\/author\/audreyf\/"}]}},"jetpack_featured_media_url":"https:\/\/arpenterlechemin.com\/wp-content\/uploads\/2016\/08\/Titre-tables-Qu\u00e9bec.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8z9hR-9v","jetpack-related-posts":[{"id":5659,"url":"https:\/\/arpenterlechemin.com\/index.php\/2018\/07\/31\/hebergements-insolites-gaspesie\/","url_meta":{"origin":589,"position":0},"title":"QU\u00c9BEC \/\/ H\u00e9bergements insolites en Gasp\u00e9sie","date":"31 juillet 2018","format":false,"excerpt":"Pendant ma semaine en Gasp\u00e9sie, j'ai eu l'occasion de loger dans trois h\u00e9bergements tr\u00e8s diff\u00e9rents mais tous aussi d\u00e9licieux les uns que les autres. La Gasp\u00e9sie, c'est une r\u00e9gion montagneuse au bord de la mer, o\u00f9 l'\u00e2me est fa\u00e7onn\u00e9e par le vent de l'Atlantique et les humeurs de la for\u00eat,\u2026","rel":"","context":"Dans &quot;Am\u00e9rique du Nord&quot;","img":{"alt_text":"hebergements gaspesie quebec blog voyage titre bonnes adresses","src":"https:\/\/i0.wp.com\/arpenterlechemin.com\/wp-content\/uploads\/2018\/07\/hebergements-gaspesie-quebec-blog-voyage-titre-bonnes-adresses.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4537,"url":"https:\/\/arpenterlechemin.com\/index.php\/2018\/01\/09\/quebec-trois-lieux-admirer-quebec-den-haut\/","url_meta":{"origin":589,"position":1},"title":"QU\u00c9BEC \/\/ Trois lieux pour admirer Qu\u00e9bec d&rsquo;en haut","date":"9 janvier 2018","format":false,"excerpt":"Le hasard fait parfois bien les choses. Lors de ma visite \u00e0 Qu\u00e9bec fin d\u00e9cembre, j'ai encha\u00een\u00e9 les activit\u00e9s en hauteur et j'ai eu envie de vous concocter un petit itin\u00e9raire pour prendre de l'altitude. Parce que mon pied alpin recherche naturellement l'altitude, parce que j'ai du mal \u00e0 m'orienter\u2026","rel":"","context":"Dans &quot;Am\u00e9rique du Nord&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/arpenterlechemin.com\/wp-content\/uploads\/2018\/01\/Qu\u00e9bec-vue-den-haut.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11258,"url":"https:\/\/arpenterlechemin.com\/index.php\/2022\/03\/31\/visiter-trois-rivieres-quebec\/","url_meta":{"origin":589,"position":2},"title":"QU\u00c9BEC \/\/ 48 heures \u00e0 Trois-Rivi\u00e8res","date":"31 mars 2022","format":false,"excerpt":"Entre Montr\u00e9al et Qu\u00e9bec se trouve une ville trop souvent d\u00e9laiss\u00e9e au profit de ses deux grandes voisines : Trois-Rivi\u00e8res, nich\u00e9e au bord du Saint-Laurent et riche de nombreux secrets bien gard\u00e9s. Que vous soyez en voyage au Qu\u00e9bec ou \u00e0 la recherche d'une escapade en Mauricie, la deuxi\u00e8me plus\u2026","rel":"","context":"Dans &quot;Am\u00e9rique du Nord&quot;","img":{"alt_text":"Visiter Trois-Rivi\u00e8res en hiver et au printemps","src":"https:\/\/i0.wp.com\/arpenterlechemin.com\/wp-content\/uploads\/2022\/03\/Visiter-Trois-Rivi\u00e8res-en-hiver-et-au-printemps.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4497,"url":"https:\/\/arpenterlechemin.com\/index.php\/2017\/12\/26\/vieux-quebec-temps-fetes\/","url_meta":{"origin":589,"position":3},"title":"QU\u00c9BEC \/\/ Le Vieux Qu\u00e9bec au temps des f\u00eates","date":"26 d\u00e9cembre 2017","format":false,"excerpt":"En Am\u00e9rique du Nord, Qu\u00e9bec a une place assez sp\u00e9ciale : une grande ville presque enti\u00e8rement francophone, la seule ville fortifi\u00e9e au nord du Mexique, une ville aux airs d'Europe avec ses rues pi\u00e9tonnes et ses fa\u00e7ades pr\u00e9serv\u00e9es, son h\u00f4tel Frontenac qui toise la ville avec de grands airs de\u2026","rel":"","context":"Dans &quot;Am\u00e9rique du Nord&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/arpenterlechemin.com\/wp-content\/uploads\/2018\/01\/Le-vieux-Qu\u00e9bec-au-temps-des-f\u00eates.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11680,"url":"https:\/\/arpenterlechemin.com\/index.php\/2022\/06\/30\/temiscouata-escapade\/","url_meta":{"origin":589,"position":4},"title":"QU\u00c9BEC \/\/ Escapade estivale dans le T\u00e9miscouata","date":"30 juin 2022","format":false,"excerpt":"Adeptes des grands espaces et du plein air, des endroits secrets et d'un ciel grand comme \u00e7a, r\u00e9jouissez-vous ! Le T\u00e9miscouata, nich\u00e9 dans le Bas-Saint-Laurent entre Rivi\u00e8re-du-Loup et le Nouveau-Brunswick, est une de ces petites p\u00e9pites dont on revient en se disant qu'on est d\u00e9cid\u00e9ment bien au Qu\u00e9bec. Une escapade\u2026","rel":"","context":"Dans &quot;Am\u00e9rique du Nord&quot;","img":{"alt_text":"Escapade dans le T\u00e9miscouata Bas-Saint-Laurent Qu\u00e9bec","src":"https:\/\/i0.wp.com\/arpenterlechemin.com\/wp-content\/uploads\/2022\/06\/Escapade-dans-le-T\u00e9miscouata-Bas-Saint-Laurent-Qu\u00e9bec-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10943,"url":"https:\/\/arpenterlechemin.com\/index.php\/2022\/12\/15\/montreal-escale-noel\/","url_meta":{"origin":589,"position":5},"title":"QU\u00c9BEC \/\/ Escale de No\u00ebl \u00e0 Montr\u00e9al","date":"15 d\u00e9cembre 2022","format":false,"excerpt":"Que faire quand on a un billet d'avion \u00e0 prix d\u00e9fiant toute concurrence mais qui nous impose une escale de 24 heures \u00e0 Montr\u00e9al ? On s'y plie de bonne gr\u00e2ce en profitant de l'aubaine au maximum, bien \u00e9videmment ! Bien s\u00fbr, la deuxi\u00e8me plus grande ville du Canada m\u00e9rite\u2026","rel":"","context":"Dans &quot;Am\u00e9rique du Nord&quot;","img":{"alt_text":"Que faire escale d\u00e9cembre Montr\u00e9al Qu\u00e9bec Canada","src":"https:\/\/i0.wp.com\/arpenterlechemin.com\/wp-content\/uploads\/2022\/12\/Que-faire-escale-d\u00e9cembre-Montr\u00e9al-Qu\u00e9bec-Canada.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/posts\/589"}],"collection":[{"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/comments?post=589"}],"version-history":[{"count":0,"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/posts\/589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/media\/400"}],"wp:attachment":[{"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/media?parent=589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/categories?post=589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arpenterlechemin.com\/index.php\/wp-json\/wp\/v2\/tags?post=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}